{"id":7966,"date":"2026-03-30T21:43:52","date_gmt":"2026-03-30T19:43:52","guid":{"rendered":"https:\/\/ecole-steiner-verrieres.org\/?p=7966"},"modified":"2026-03-30T21:45:59","modified_gmt":"2026-03-30T19:45:59","slug":"presentation-des-chefs-doeuvre-de-la-12e-classe-2026","status":"publish","type":"post","link":"https:\/\/ecole-steiner-verrieres.org\/en\/presentation-des-chefs-doeuvre-de-la-12e-classe-2026\/","title":{"rendered":"Pr\u00e9sentation des chefs-d&#8217;\u0153uvre de la 12e classe 2026"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>Dans l\u2019imaginaire collectif, le terme \u00abchef-d\u2019\u0153uvre\u00bb \u00e9voque un travail capital et difficile, accompli par un artisan qui a atteint la ma\u00eetrise dans son domaine.<\/p>\n\n\n\n<p>Les travaux de fin de cycle dans notre \u00e9cole sont commun\u00e9ment appel\u00e9s \u00abchefs-d\u2019\u0153uvre\u00bb. Ils conservent du sens originel le caract\u00e8re difficile, le d\u00e9fi qu\u2019ils repr\u00e9sentent \u00e0 l\u2019\u00e9chelle d\u2019un jeune dans sa dix-huiti\u00e8me ann\u00e9e. Ils sont \u00e9galement l\u2019aboutissement d\u2019un cycle (parfois de 15 ans) dans l\u2019\u00e9tablissement. Ce travail exige de l\u2019\u00e9l\u00e8ve qu\u2019il s\u2019engage dans un processus pour concr\u00e9tiser un projet choisi dans des domaines tr\u00e8s vari\u00e9s. Pour le mener \u00e0 bien, l\u2019\u00e9l\u00e8ve est amen\u00e9 \u00e0 puiser dans ses propres forces. Il est cependant accompagn\u00e9 et soutenu sur ce chemin par un professeur, qu\u2019il choisit comme \u00abmarraine\u00bb ou \u00abparrain\u00bb de son projet, et \u00e9galement par d\u2019autres adultes de son entourage.<\/p>\n\n\n\n<p>Lors de ce partage devant les \u00e9l\u00e8ves, les parents, les professeurs et les amis, chaque jeune de 12e classe d\u00e9couvre alors et exprime qu\u2019il tire au moins autant un enseignement de l\u2019exp\u00e9rience v\u00e9cue au cours de la recherche, que de l&#8217;aboutissement concret du projet en tant que tel.<\/p>\n\n\n\n<p><strong>Samedi 11 avril 2026 de 12 heures \u00e0 21h30. <\/strong><\/p>\n\n\n\n<p><em><strong>\u00c9v\u00e9nement ouvert aux \u00e9l\u00e8ves, aux professeurs, aux familles de l&#8217;\u00e9cole et aux amis.<\/strong><\/em><\/p>\n\n\n\n<p>Un buffet (payant) sera tenu par la 11e classe au profit de leur projet th\u00e9\u00e2tre.<\/p>\n\n\n\n<p><strong>Salle Odilon-Redon<\/strong> de l&#8217;\u00e9cole Steiner 62 rue de Paris \u00e0 Verri\u00e8res-le-Buisson. Parking au 21, route de Bi\u00e8vres.<\/p>","protected":false},"excerpt":{"rendered":"<p>Samedi 11 avril 2026 de 12h \u00e0 21h30. <\/p>","protected":false},"author":3,"featured_media":7963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"page_builder":"","footnotes":""},"categories":[13],"tags":[67],"class_list":["post-7966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-evenement"],"_links":{"self":[{"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/posts\/7966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/comments?post=7966"}],"version-history":[{"count":2,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/posts\/7966\/revisions"}],"predecessor-version":[{"id":7968,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/posts\/7966\/revisions\/7968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/media\/7963"}],"wp:attachment":[{"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/media?parent=7966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/categories?post=7966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/tags?post=7966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}