{"id":2137,"date":"2021-11-03T15:00:11","date_gmt":"2021-11-03T14:00:11","guid":{"rendered":"http:\/\/ecole-steiner-verrieres.org\/?page_id=2137"},"modified":"2026-04-22T15:01:56","modified_gmt":"2026-04-22T13:01:56","slug":"inscriptions","status":"publish","type":"page","link":"https:\/\/ecole-steiner-verrieres.org\/en\/inscriptions\/","title":{"rendered":"Inscriptions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2137\" class=\"elementor elementor-2137\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8e6e40 e-flex e-con-boxed e-con e-parent\" data-id=\"f8e6e40\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;,&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n    <path class=\"elementor-shape-fill\" d=\"M1000,4.3V0H0v4.3C0.9,23.1,126.7,99.2,500,100S1000,22.7,1000,4.3z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0674740 e-con-full e-flex e-con e-child\" data-id=\"0674740\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c65740 elementor-widget elementor-widget-spacer\" data-id=\"5c65740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a28a07e e-con-full e-flex e-con e-child\" data-id=\"a28a07e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8a0047c elementor-hidden-tablet elementor-hidden-mobile e-con-full e-flex e-con e-child\" data-id=\"8a0047c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5236bf6 elementor-nav-menu__align-center elementor-nav-menu__text-align-center elementor-hidden-tablet elementor-hidden-mobile elementor-nav-menu--dropdown-tablet elementor-widget elementor-widget-nav-menu\" data-id=\"5236bf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i aria-hidden=\\&quot;true\\&quot; class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-overline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-5236bf6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-544\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">L&#8217;\u00e9cole<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-633\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/decouvrir\/\" class=\"elementor-sub-item\">D\u00e9couvrir l\u2019\u00e9cole<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7852\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/foire-aux-questions\/\" class=\"elementor-sub-item\">Foire aux questions<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-800\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/jardin-denfants\/\" class=\"elementor-sub-item\">Jardin d\u2019enfants<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-584\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/primaire\/\" class=\"elementor-sub-item\">Primaire<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-811\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/college\/\" class=\"elementor-sub-item\">Coll\u00e8ge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1278\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/lycee\/\" class=\"elementor-sub-item\">Lyc\u00e9e<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-545\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">La p\u00e9dagogie<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1391\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/pedagogie-steiner-waldorf\/\" class=\"elementor-sub-item\">La p\u00e9dagogie Steiner-Waldorf<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2484\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/les-atouts-de-la-pedagogie\/\" class=\"elementor-sub-item\">Les atouts de la p\u00e9dagogie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2483\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/une-annee-rythmee-par-les-fetes\/\" class=\"elementor-sub-item\">Une ann\u00e9e rythm\u00e9e par les f\u00eates<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5236bf6\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-544\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">L&#8217;\u00e9cole<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-633\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/decouvrir\/\" class=\"elementor-sub-item\" tabindex=\"-1\">D\u00e9couvrir l\u2019\u00e9cole<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7852\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/foire-aux-questions\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Foire aux questions<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-800\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/jardin-denfants\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Jardin d\u2019enfants<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-584\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/primaire\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Primaire<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-811\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/college\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Coll\u00e8ge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1278\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/lycee\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Lyc\u00e9e<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-545\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">La p\u00e9dagogie<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1391\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/pedagogie-steiner-waldorf\/\" class=\"elementor-sub-item\" tabindex=\"-1\">La p\u00e9dagogie Steiner-Waldorf<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2484\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/les-atouts-de-la-pedagogie\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Les atouts de la p\u00e9dagogie<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2483\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/une-annee-rythmee-par-les-fetes\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Une ann\u00e9e rythm\u00e9e par les f\u00eates<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca8bdf2 e-con-full e-flex e-con e-child\" data-id=\"ca8bdf2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70567a7 elementor-widget elementor-widget-image\" data-id=\"70567a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ecole-steiner-verrieres.org\/en\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ecole-steiner-verrieres.org\/gloagrom\/2021\/10\/Logo_VLB.svg\" class=\"attachment-full size-full wp-image-875\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58b802f elementor-hidden-tablet elementor-hidden-mobile e-con-full e-flex e-con e-child\" data-id=\"58b802f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42708c4 elementor-nav-menu__align-center elementor-nav-menu__text-align-center elementor-hidden-tablet elementor-hidden-mobile elementor-nav-menu--dropdown-tablet elementor-widget elementor-widget-nav-menu\" data-id=\"42708c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i aria-hidden=\\&quot;true\\&quot; class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-overline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-42708c4\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-546\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Vie de l&#8217;\u00e9cole<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2243\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/actualites\/\" class=\"elementor-sub-item\">Actualit\u00e9s de l\u2019\u00e9cole<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1716\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/ateliers-parents-enfants\/\" class=\"elementor-sub-item\">Ateliers parents &#038; enfants<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1790\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/collaborations-parents-professeurs\/\" class=\"elementor-sub-item\">Collaborations parents &#038; professeurs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3131\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/resultats-aux-examens\/\" class=\"elementor-sub-item\">R\u00e9sultats aux examens et orientation<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3485\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/offres-demploi\/\" class=\"elementor-sub-item\">Offres d\u2019emploi<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-547\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">T\u00e9moignages<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2303\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/temoignages\/\" class=\"elementor-sub-item\">T\u00e9moignages parents, \u00e9l\u00e8ves<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2287\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/ressources\/\" class=\"elementor-sub-item\">M\u00e9dias<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2353\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/partenaires\/\" class=\"elementor-sub-item\">En savoir plus<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-42708c4\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-546\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Vie de l&#8217;\u00e9cole<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2243\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/actualites\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Actualit\u00e9s de l\u2019\u00e9cole<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1716\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/ateliers-parents-enfants\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ateliers parents &#038; enfants<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1790\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/collaborations-parents-professeurs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Collaborations parents &#038; professeurs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3131\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/resultats-aux-examens\/\" class=\"elementor-sub-item\" tabindex=\"-1\">R\u00e9sultats aux examens et orientation<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3485\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/offres-demploi\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Offres d\u2019emploi<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-547\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">T\u00e9moignages<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2303\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/temoignages\/\" class=\"elementor-sub-item\" tabindex=\"-1\">T\u00e9moignages parents, \u00e9l\u00e8ves<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2287\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/ressources\/\" class=\"elementor-sub-item\" tabindex=\"-1\">M\u00e9dias<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2353\"><a href=\"https:\/\/ecole-steiner-verrieres.org\/en\/partenaires\/\" class=\"elementor-sub-item\" tabindex=\"-1\">En savoir plus<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ae3163 elementor-widget elementor-widget-heading\" data-id=\"9ae3163\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/aa\">Bienvenue<br>\u00e0 l'\u00e9cole Steiner Waldorf<br>de Verri\u00e8res-Le-Buisson<\/a><\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d55427 elementor-hidden-phone e-con-full e-flex e-con e-child\" data-id=\"7d55427\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d4acf4 e-con-full e-flex e-con e-child\" data-id=\"3d4acf4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dcd6c6 e-con-full e-flex e-con e-child\" data-id=\"2dcd6c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da94cc6 elementor-widget elementor-widget-image\" data-id=\"da94cc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ecole-steiner-verrieres.org\/gloagrom\/2021\/10\/Fleur_vie-mutlicolore.svg\" class=\"attachment-full size-full wp-image-957\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e78cc5 e-con-full e-flex e-con e-child\" data-id=\"0e78cc5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41e3865 e-con-full e-flex e-con e-parent\" data-id=\"41e3865\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-445f857 elementor-widget elementor-widget-heading\" data-id=\"445f857\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Vous souhaitez inscrire votre enfant\u00a0?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5beb01a elementor-widget elementor-widget-text-editor\" data-id=\"5beb01a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h5><em>C\u2019est tr\u00e8s simple\u00a0!<\/em><\/h5><p><strong>Les inscriptions sont possibles toute l\u2019ann\u00e9e pour toutes les sections, de la Maternelle \u00e0 la Terminale.<\/strong><\/p><p><strong>Merci d\u2019envoyer votre demande via le formulaire ci-dessous <br \/>ou bien<br \/>de nous joindre par t\u00e9l\u00e9phone au <a href=\"tel:0160113812\">01 60 11 38 12<\/a><\/strong><\/p><p><span style=\"font-size: 1rem;\">Une fois la demande en ligne envoy\u00e9e, et sous deux semaines, un professeur vous contactera pour vous proposer \u00e9ventuellement un rendez-vous p\u00e9dagogique, pour lequel la pr\u00e9sence de l\u2019enfant et de ses deux parents est requise.<\/span><\/p><p>Suite \u00e0 ce rendez-vous, un des deux professeurs vous ayant re\u00e7us vous informera de la d\u00e9cision du Coll\u00e8ge des professeurs, vous confirmant ou non l\u2019inscription de votre enfant.<\/p><p>Voir la grille des <a title=\"Tarifs 2025-2026 \u00e9cole Steiner Verri\u00e8res-le-Buisson (PDF)\" href=\"http:\/\/ecole-steiner-verrieres.org\/gloagrom\/2023\/12\/Tarifs-ecole-2025-2026.pdf\" target=\"_blank\" rel=\"noopener\">tarifs 2025-2026<\/a>. Voici la grille des <a title=\"pdf tarifs \u00e9colage 2026-27\" href=\"http:\/\/ecole-steiner-verrieres.org\/gloagrom\/2023\/12\/2026-2027-Tarifs-ecole.pdf\" target=\"_blank\" rel=\"noopener\">tarifs 2026-2027<\/a>. L\u2019\u00e9cole, gr\u00e2ce au Fonds \u00c9ducations Plurielles, peut dans certaines conditions b\u00e9n\u00e9ficier d&#8217;une <strong>caisse de solidarit\u00e9<\/strong> qui octroie des <strong>bourses aux familles n\u2019ayant pas les moyens de payer tout ou partie de la scolarit\u00e9<\/strong>. <em>Si vous \u00eates dans cette situation, n\u2019h\u00e9sitez pas \u00e0 contacter l&#8217;accueil ou bien\u00a0 <\/em><a title=\"Courriel \u00e0 la caisse de solidarit\u00e9\" href=\"https:\/\/ecole-steiner-verrieres.org\/inscriptions\/\">caissedesolidarite@ecole-steiner-verrieres.org<\/a><\/p><p>Attention pour toute demande d&#8217;<b>\u00e9change \/ s\u00e9jour linguistique<\/b>, merci de nous envoyer directement une demande par email \u00e0 <a style=\"background-color: #ffffff; font-size: 1rem;\" href=\"mailto:accueil@ecole-steiner-verrieres.org\" target=\"_blank\" rel=\"noopener\">accueil@ecole-steiner-verrieres.org<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0238218 e-flex e-con-boxed e-con e-parent\" data-id=\"0238218\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a388cab e-con-full e-flex e-con e-child\" data-id=\"a388cab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cac5b2d elementor-widget elementor-widget-heading\" data-id=\"cac5b2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. D\u00e9couvrir l'\u00e9cole<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cfca6d elementor-widget elementor-widget-text-editor\" data-id=\"6cfca6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Vous souhaitez d\u00e9couvrir l&#8217;\u00e9cole ? Remplissez le formulaire ci-dessous pour \u00eatre invit\u00e9(e) aux prochains \u00e9v\u00e9nements !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-464a514 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"464a514\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Pr\u00e9inscriptions\" aria-label=\"Pr\u00e9inscriptions\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"2137\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"464a514\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Inscriptions - Ecole Steiner de Verri\u00e8res-le-Buisson\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"2137\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-prenom elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-prenom\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tPr\u00e9nom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[prenom]\" id=\"form-field-prenom\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Pr\u00e9nom\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_6c0686b elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_6c0686b\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_6c0686b]\" id=\"form-field-field_6c0686b\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-telephone elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-telephone\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tT\u00e9l\u00e9phone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[telephone]\" id=\"form-field-telephone\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"T\u00e9l\u00e9phone\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-field_3609e58 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3609e58\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tJe souhaite\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Je souhaite \u00e9galement recevoir des informations sur la p\u00e9dagogie Waldorf\" id=\"form-field-field_3609e58-0\" name=\"form_fields[field_3609e58]\"> <label for=\"form-field-field_3609e58-0\">Je souhaite \u00e9galement recevoir des informations sur la p\u00e9dagogie Waldorf<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-recaptcha elementor-col-100 recaptcha_v3-bottomleft\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-recaptcha\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LeD9fscAAAAAH2Tul-OzxrxVmg2zgmtWNDCTn6o\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomleft\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b4a2ac e-con-full e-flex e-con e-child\" data-id=\"8b4a2ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90fc28c elementor-widget elementor-widget-heading\" data-id=\"90fc28c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Remplir une demande de pr\u00e9inscription<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-281abfa elementor-widget elementor-widget-text-editor\" data-id=\"281abfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>En cliquant sur le lien suivant, vous pourrez remplir une demande de pr\u00e9inscription compl\u00e8te.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e9a739 elementor-widget elementor-widget-button\" data-id=\"9e9a739\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/preinscriptions.ecoledirecte.com\/?RNE=0911601W\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Remplir le dossier de pr\u00e9inscription<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5335452 elementor-widget elementor-widget-text-editor\" data-id=\"5335452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Vous pouvez aussi <a href=\"http:\/\/ecole-steiner-verrieres.org\/gloagrom\/2021\/11\/Ecole-Steiner-Verrieres-tableau-correspondance-ages.pdf\" target=\"_blank\" rel=\"noopener\">t\u00e9l\u00e9charger la correspondance des \u00e2ges par classe<\/a> (n&#8217;h\u00e9sitez pas \u00e0 nous appeler pour en savoir plus sur la classe o\u00f9 serait inscrit votre enfant suite \u00e0 la modification de notre cycle \u00e9l\u00e9mentaire).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a463f06 e-flex e-con-boxed e-con e-parent\" data-id=\"a463f06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0489447 e-con-full e-flex e-con e-child\" data-id=\"0489447\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0f952f elementor-hidden-phone e-con-full e-flex e-con e-child\" data-id=\"e0f952f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2735c94 elementor-widget elementor-widget-spacer\" data-id=\"2735c94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-710ffc9 elementor-widget elementor-widget-heading\" data-id=\"710ffc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les horaires de l'\u00e9cole<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67137e6 elementor-widget elementor-widget-text-editor\" data-id=\"67137e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\"><span style=\"text-decoration: underline;\"><em><strong>Les cours<\/strong><\/em><\/span><br \/>L\u2019ouverture de l\u2019\u00e9cole se fait \u00e0 8h30 pour un d\u00e9but des cours \u00e0 8h45.<\/span><\/p><p><span style=\"font-weight: 400;\"><strong>Jardins d\u2019enfants :<\/strong> 8h45-15h45 lundi, mardi, jeudi, vendredi ; 8h45-13h le mercredi.<\/span><\/p><p><strong>1e et 2e<\/strong><span style=\"font-weight: 400;\"><strong> classes (CP et CE1) :<\/strong> 8h45-15h45 lundi, mardi, jeudi ; 8h45-13h mercredi ; 8h45-13h vendredi (un temps de \u201cplein air\u201d est propos\u00e9 le vendredi apr\u00e8s-midi).<\/span><\/p><p><strong>3e et 4e<\/strong><span style=\"font-weight: 400;\"><strong> classes (CE2 et CM1) :<\/strong> 8h45-15h45 lundi, mardi, jeudi, vendredi ; 8h45-13h mercredi.<\/span><\/p><p><strong>5e c<\/strong><span style=\"font-weight: 400;\"><strong>lasse (CM2) :<\/strong> 8h45-15h45 lundi, mardi, mercredi, jeudi, vendredi.<\/span><\/p><p><span style=\"font-weight: 400;\"><strong>Coll\u00e8ge :<\/strong> 8h45-15h45 du lundi au vendredi, certains jours fin des cours \u00e0 16h40 ou 17h35.<\/span><\/p><p><span style=\"font-weight: 400;\"><strong>Lyc\u00e9e :<\/strong> d\u00e9but des cours \u00e0 8h45 ; heure de fin des cours variable, horaires plus \u00e9tendus (sp\u00e9cialit\u00e9s).<\/span><\/p><p><span style=\"font-weight: 400;\">Les \u00e9l\u00e8ves des jardins d\u2019enfants et des petites classes peuvent \u00eatre inscrits \u00e0 la garderie de l\u2019\u00e9cole.<\/span><\/p><p><span style=\"text-decoration: underline;\"><em><strong>Les r\u00e9cr\u00e9ations<br \/><\/strong><\/em><\/span><strong>R\u00e9cr\u00e9ations 1e \u00e0 5e<\/strong><span style=\"font-weight: 400;\"><strong> classe :<\/strong> 10h35\u201311h, 13h\u201313h45, 14h35\u201314h50<\/span><\/p><p><strong>R\u00e9cr\u00e9ations \u00e0 partir de la 6e<\/strong><span style=\"font-weight: 400;\"><strong> classe :<\/strong> 10h40\u2013 11h05, 13h25\u201314h<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29579a7 elementor-widget elementor-widget-heading\" data-id=\"29579a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les vacances scolaires<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7eaace6 elementor-widget elementor-widget-text-editor\" data-id=\"7eaace6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La date de la rentr\u00e9e en septembre et les vacances scolaires sont celles de l\u2019\u00c9ducation Nationale.<\/span><\/p><p><span style=\"font-weight: 400;\">En ce qui concerne la date de fin des cours (d\u00e9but juillet), celle-ci est confirm\u00e9e en cours d\u2019ann\u00e9e dans le bloc-notes envoy\u00e9 aux familles.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5d4476 elementor-widget elementor-widget-spacer\" data-id=\"e5d4476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3840d94 e-con-full e-flex e-con e-child\" data-id=\"3840d94\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bienvenue\u00e0 l&#8217;\u00e9cole Steiner Waldorfde Verri\u00e8res-Le-Buisson Vous souhaitez inscrire votre enfant\u00a0? C\u2019est tr\u00e8s simple\u00a0! Les inscriptions sont possibles toute l\u2019ann\u00e9e pour toutes les sections, de la Maternelle \u00e0 la Terminale. Merci [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":14,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_angie_page":false,"footnotes":""},"class_list":["post-2137","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/pages\/2137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/comments?post=2137"}],"version-history":[{"count":57,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/pages\/2137\/revisions"}],"predecessor-version":[{"id":8071,"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/pages\/2137\/revisions\/8071"}],"wp:attachment":[{"href":"https:\/\/ecole-steiner-verrieres.org\/en\/wp-json\/wp\/v2\/media?parent=2137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}